{"id":9,"date":"2016-09-13T20:36:48","date_gmt":"2016-09-13T20:36:48","guid":{"rendered":"http:\/\/research.monm.edu\/conference\/?page_id=9"},"modified":"2021-10-12T09:55:50","modified_gmt":"2021-10-12T14:55:50","slug":"2017-conference-of-undergraduate-research-scholarship","status":"publish","type":"page","link":"http:\/\/research.monm.edu\/conference\/","title":{"rendered":"2022 Conference of Undergraduate Research &#038; Scholarship"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full-width.php","meta":{"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/research.monm.edu\/conference\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/research.monm.edu\/conference\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/research.monm.edu\/conference\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/research.monm.edu\/conference\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/research.monm.edu\/conference\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":8,"href":"http:\/\/research.monm.edu\/conference\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":246,"href":"http:\/\/research.monm.edu\/conference\/wp-json\/wp\/v2\/pages\/9\/revisions\/246"}],"wp:attachment":[{"href":"http:\/\/research.monm.edu\/conference\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}